{"id":2380,"date":"2022-12-01T18:00:47","date_gmt":"2022-12-01T17:00:47","guid":{"rendered":"https:\/\/www.pieps.com\/t-schaufeln\/"},"modified":"2022-12-01T18:08:16","modified_gmt":"2022-12-01T17:08:16","slug":"t-shovels","status":"publish","type":"page","link":"https:\/\/www.pieps.com\/en\/t-shovels\/","title":{"rendered":"T-SHOVELS"},"content":{"rendered":"<div class=\"l-container\"><div class=\"l-gutenberg-block \"><section id=\"product-series-block_e34f8c42e0b2036b1dc3d4c212920369\" class=\"c-product-series \">\n  <div class=\"c-product-series__title\"><h1 class=\"\">T-SHOVELS<\/h1><\/div>\n\n      <div class=\"c-product-series__entries\">\n      <div class=\"l-row l-row--gap-small\">\n        \n          <div class=\"l-col l-col-4 l-col-l-6 l-col-m-12\">\n                                        <div class=\"c-product-series__entry\">\n                <div class=\"c-product-series__entry-title\">SHOVEL T500<\/div>\n                <div class=\"c-product-series__entry-description\"><\/div>\n\n                  <a class=\"c-product-series__entry-product-image-holder has-glow\" href=\"https:\/\/www.pieps.com\/en\/product\/shovel-t500\/\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"1772\" height=\"2657\" src=\"https:\/\/www.pieps.com\/wp-content\/uploads\/2022\/10\/shovel_t500_web.png\" class=\"attachment-archive size-archive\" alt=\"SHOVEL T500\" srcset=\"https:\/\/www.pieps.com\/wp-content\/uploads\/2022\/10\/shovel_t500_web.png 1772w, https:\/\/www.pieps.com\/wp-content\/uploads\/2022\/10\/shovel_t500_web-200x300.png 200w, https:\/\/www.pieps.com\/wp-content\/uploads\/2022\/10\/shovel_t500_web-768x1152.png 768w, https:\/\/www.pieps.com\/wp-content\/uploads\/2022\/10\/shovel_t500_web-683x1024.png 683w, https:\/\/www.pieps.com\/wp-content\/uploads\/2022\/10\/shovel_t500_web-1024x1536.png 1024w, https:\/\/www.pieps.com\/wp-content\/uploads\/2022\/10\/shovel_t500_web-1366x2048.png 1366w, https:\/\/www.pieps.com\/wp-content\/uploads\/2022\/10\/shovel_t500_web-267x400.png 267w, https:\/\/www.pieps.com\/wp-content\/uploads\/2022\/10\/shovel_t500_web-600x900.png 600w\" sizes=\"auto, (max-width: 1772px) 100vw, 1772px\" \/>                  <\/a>\n                  <div class=\"c-product-series__entry-product-title\">Pieps <strong>SHOVEL T500<\/strong><\/div>\n                  <a class=\"o-button o-button--white o-button--hover-secondary c-product-series__entry-product-button\" href=\"https:\/\/www.pieps.com\/en\/product\/shovel-t500\/\">\n                    <span class=\"o-button__text\">Learn more<\/span>\n                  <\/a>\n              <\/div>\n                                    <\/div>\n\n        \n          <div class=\"l-col l-col-4 l-col-l-6 l-col-m-12\">\n                                        <div class=\"c-product-series__entry\">\n                <div class=\"c-product-series__entry-title\">SHOVEL T640<\/div>\n                <div class=\"c-product-series__entry-description\"><\/div>\n\n                  <a class=\"c-product-series__entry-product-image-holder has-glow\" href=\"https:\/\/www.pieps.com\/en\/product\/shovel-t640\/\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"2362\" height=\"3543\" src=\"https:\/\/www.pieps.com\/wp-content\/uploads\/2022\/10\/shovel_t640_telescope_web.png\" class=\"attachment-archive size-archive\" alt=\"SHOVEL T640\" srcset=\"https:\/\/www.pieps.com\/wp-content\/uploads\/2022\/10\/shovel_t640_telescope_web.png 2362w, https:\/\/www.pieps.com\/wp-content\/uploads\/2022\/10\/shovel_t640_telescope_web-200x300.png 200w, https:\/\/www.pieps.com\/wp-content\/uploads\/2022\/10\/shovel_t640_telescope_web-768x1152.png 768w, https:\/\/www.pieps.com\/wp-content\/uploads\/2022\/10\/shovel_t640_telescope_web-683x1024.png 683w, https:\/\/www.pieps.com\/wp-content\/uploads\/2022\/10\/shovel_t640_telescope_web-1024x1536.png 1024w, https:\/\/www.pieps.com\/wp-content\/uploads\/2022\/10\/shovel_t640_telescope_web-1365x2048.png 1365w, https:\/\/www.pieps.com\/wp-content\/uploads\/2022\/10\/shovel_t640_telescope_web-267x400.png 267w, https:\/\/www.pieps.com\/wp-content\/uploads\/2022\/10\/shovel_t640_telescope_web-600x900.png 600w\" sizes=\"auto, (max-width: 2362px) 100vw, 2362px\" \/>                  <\/a>\n                  <div class=\"c-product-series__entry-product-title\">Pieps <strong>SHOVEL T640<\/strong><\/div>\n                  <a class=\"o-button o-button--white o-button--hover-secondary c-product-series__entry-product-button\" href=\"https:\/\/www.pieps.com\/en\/product\/shovel-t640\/\">\n                    <span class=\"o-button__text\">Learn more<\/span>\n                  <\/a>\n              <\/div>\n                                    <\/div>\n\n        \n          <div class=\"l-col l-col-4 l-col-l-6 l-col-m-12\">\n                                        <div class=\"c-product-series__entry\">\n                <div class=\"c-product-series__entry-title\">SHOVEL T705<\/div>\n                <div class=\"c-product-series__entry-description\"><\/div>\n\n                  <a class=\"c-product-series__entry-product-image-holder has-glow\" href=\"https:\/\/www.pieps.com\/en\/product\/shovel-t705\/\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"1929\" height=\"2894\" src=\"https:\/\/www.pieps.com\/wp-content\/uploads\/2022\/10\/pieps_shovel_t705_rgb_web.png\" class=\"attachment-archive size-archive\" alt=\"SHOVEL T705\" srcset=\"https:\/\/www.pieps.com\/wp-content\/uploads\/2022\/10\/pieps_shovel_t705_rgb_web.png 1929w, https:\/\/www.pieps.com\/wp-content\/uploads\/2022\/10\/pieps_shovel_t705_rgb_web-200x300.png 200w, https:\/\/www.pieps.com\/wp-content\/uploads\/2022\/10\/pieps_shovel_t705_rgb_web-768x1152.png 768w, https:\/\/www.pieps.com\/wp-content\/uploads\/2022\/10\/pieps_shovel_t705_rgb_web-683x1024.png 683w, https:\/\/www.pieps.com\/wp-content\/uploads\/2022\/10\/pieps_shovel_t705_rgb_web-1024x1536.png 1024w, https:\/\/www.pieps.com\/wp-content\/uploads\/2022\/10\/pieps_shovel_t705_rgb_web-1365x2048.png 1365w, https:\/\/www.pieps.com\/wp-content\/uploads\/2022\/10\/pieps_shovel_t705_rgb_web-267x400.png 267w, https:\/\/www.pieps.com\/wp-content\/uploads\/2022\/10\/pieps_shovel_t705_rgb_web-600x900.png 600w\" sizes=\"auto, (max-width: 1929px) 100vw, 1929px\" \/>                  <\/a>\n                  <div class=\"c-product-series__entry-product-title\">Pieps <strong>SHOVEL T705<\/strong><\/div>\n                  <a class=\"o-button o-button--white o-button--hover-secondary c-product-series__entry-product-button\" href=\"https:\/\/www.pieps.com\/en\/product\/shovel-t705\/\">\n                    <span class=\"o-button__text\">Learn more<\/span>\n                  <\/a>\n              <\/div>\n                                    <\/div>\n\n        \n          <div class=\"l-col l-col-4 l-col-l-6 l-col-m-12\">\n                                        <div class=\"c-product-series__entry\">\n                <div class=\"c-product-series__entry-title\">SHOVEL T825 pro+<\/div>\n                <div class=\"c-product-series__entry-description\"><\/div>\n\n                  <a class=\"c-product-series__entry-product-image-holder has-glow\" href=\"https:\/\/www.pieps.com\/en\/product\/shovel-t825-pro\/\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"2756\" height=\"4134\" src=\"https:\/\/www.pieps.com\/wp-content\/uploads\/2022\/10\/pieps_shovel_t825_with_saw.png\" class=\"attachment-archive size-archive\" alt=\"SHOVEL T825 pro+\" srcset=\"https:\/\/www.pieps.com\/wp-content\/uploads\/2022\/10\/pieps_shovel_t825_with_saw.png 2756w, https:\/\/www.pieps.com\/wp-content\/uploads\/2022\/10\/pieps_shovel_t825_with_saw-200x300.png 200w, https:\/\/www.pieps.com\/wp-content\/uploads\/2022\/10\/pieps_shovel_t825_with_saw-768x1152.png 768w, https:\/\/www.pieps.com\/wp-content\/uploads\/2022\/10\/pieps_shovel_t825_with_saw-683x1024.png 683w, https:\/\/www.pieps.com\/wp-content\/uploads\/2022\/10\/pieps_shovel_t825_with_saw-1024x1536.png 1024w, https:\/\/www.pieps.com\/wp-content\/uploads\/2022\/10\/pieps_shovel_t825_with_saw-1365x2048.png 1365w, https:\/\/www.pieps.com\/wp-content\/uploads\/2022\/10\/pieps_shovel_t825_with_saw-267x400.png 267w, https:\/\/www.pieps.com\/wp-content\/uploads\/2022\/10\/pieps_shovel_t825_with_saw-600x900.png 600w\" sizes=\"auto, (max-width: 2756px) 100vw, 2756px\" \/>                  <\/a>\n                  <div class=\"c-product-series__entry-product-title\">Pieps <strong>SHOVEL T825 pro+<\/strong><\/div>\n                  <a class=\"o-button o-button--white o-button--hover-secondary c-product-series__entry-product-button\" href=\"https:\/\/www.pieps.com\/en\/product\/shovel-t825-pro\/\">\n                    <span class=\"o-button__text\">Learn more<\/span>\n                  <\/a>\n              <\/div>\n                                    <\/div>\n\n              <\/div>\n    <\/div>\n  <\/section>\n<\/div><\/div>\n\n<div class=\"l-container\">\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div><!--CORE: l-container-->","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-2380","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>T-SHOVELS - PIEPS GmbH<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pieps.com\/t-schaufeln\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"T-SHOVELS - PIEPS GmbH\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pieps.com\/t-schaufeln\/\" \/>\n<meta property=\"og:site_name\" content=\"PIEPS GmbH\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/piepstechnology\/\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-01T17:08:16+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.pieps.com\\\/t-schaufeln\\\/\",\"url\":\"https:\\\/\\\/www.pieps.com\\\/t-schaufeln\\\/\",\"name\":\"T-SHOVELS - PIEPS GmbH\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pieps.com\\\/#website\"},\"datePublished\":\"2022-12-01T17:00:47+00:00\",\"dateModified\":\"2022-12-01T17:08:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.pieps.com\\\/t-schaufeln\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.pieps.com\\\/t-schaufeln\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.pieps.com\\\/t-schaufeln\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Start\",\"item\":\"https:\\\/\\\/www.pieps.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"T-SHOVELS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.pieps.com\\\/#website\",\"url\":\"https:\\\/\\\/www.pieps.com\\\/\",\"name\":\"PIEPS GmbH\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.pieps.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.pieps.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.pieps.com\\\/#organization\",\"name\":\"PIEPS GmbH\",\"url\":\"https:\\\/\\\/www.pieps.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.pieps.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.pieps.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/pieps_logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.pieps.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/pieps_logo.svg\",\"width\":1,\"height\":1,\"caption\":\"PIEPS GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pieps.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/piepstechnology\\\/\",\"https:\\\/\\\/www.instagram.com\\\/pieps_technology\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"T-SHOVELS - PIEPS GmbH","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pieps.com\/t-schaufeln\/","og_locale":"en_US","og_type":"article","og_title":"T-SHOVELS - PIEPS GmbH","og_url":"https:\/\/www.pieps.com\/t-schaufeln\/","og_site_name":"PIEPS GmbH","article_publisher":"https:\/\/www.facebook.com\/piepstechnology\/","article_modified_time":"2022-12-01T17:08:16+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.pieps.com\/t-schaufeln\/","url":"https:\/\/www.pieps.com\/t-schaufeln\/","name":"T-SHOVELS - PIEPS GmbH","isPartOf":{"@id":"https:\/\/www.pieps.com\/#website"},"datePublished":"2022-12-01T17:00:47+00:00","dateModified":"2022-12-01T17:08:16+00:00","breadcrumb":{"@id":"https:\/\/www.pieps.com\/t-schaufeln\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pieps.com\/t-schaufeln\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.pieps.com\/t-schaufeln\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Start","item":"https:\/\/www.pieps.com\/en\/"},{"@type":"ListItem","position":2,"name":"T-SHOVELS"}]},{"@type":"WebSite","@id":"https:\/\/www.pieps.com\/#website","url":"https:\/\/www.pieps.com\/","name":"PIEPS GmbH","description":"","publisher":{"@id":"https:\/\/www.pieps.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pieps.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.pieps.com\/#organization","name":"PIEPS GmbH","url":"https:\/\/www.pieps.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.pieps.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.pieps.com\/wp-content\/uploads\/2026\/04\/pieps_logo.svg","contentUrl":"https:\/\/www.pieps.com\/wp-content\/uploads\/2026\/04\/pieps_logo.svg","width":1,"height":1,"caption":"PIEPS GmbH"},"image":{"@id":"https:\/\/www.pieps.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/piepstechnology\/","https:\/\/www.instagram.com\/pieps_technology\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.pieps.com\/en\/wp-json\/wp\/v2\/pages\/2380","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pieps.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.pieps.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.pieps.com\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pieps.com\/en\/wp-json\/wp\/v2\/comments?post=2380"}],"version-history":[{"count":4,"href":"https:\/\/www.pieps.com\/en\/wp-json\/wp\/v2\/pages\/2380\/revisions"}],"predecessor-version":[{"id":2385,"href":"https:\/\/www.pieps.com\/en\/wp-json\/wp\/v2\/pages\/2380\/revisions\/2385"}],"wp:attachment":[{"href":"https:\/\/www.pieps.com\/en\/wp-json\/wp\/v2\/media?parent=2380"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}